{"id":11396,"date":"2023-12-08T23:58:44","date_gmt":"2023-12-08T22:58:44","guid":{"rendered":"https:\/\/prod.solutionscustom.ch\/nomadiq-bbq\/"},"modified":"2024-03-14T08:43:03","modified_gmt":"2024-03-14T07:43:03","slug":"nomadiq-bbq","status":"publish","type":"page","link":"https:\/\/solutionscustom.ch\/de\/distributions\/nomadiq-bbq\/","title":{"rendered":"nomadiQ BBQ"},"content":{"rendered":"\n\n  <div class=\"banner has-hover\" id=\"banner-727612192\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                    <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1114017994\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\t<div id=\"text-2069477614\" class=\"text\">\n\t\t\n\n<h3 class=\"uppercase\"><span style=\"color: #ffffff;\">OFFIZIELLER SCHWEIZERISCHER VERTREIBER<\/span><\/h3>\n\n\t\t\n<style>\n#text-2069477614 {\n  font-size: 0.75rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1114017994 {\n  width: 60%;\n}\n#text-box-1114017994 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-727612192 {\n  padding-top: 60px;\n}\n#banner-727612192 .overlay {\n  background-color: rgba(0, 0, 0, 0.17);\n}\n<\/style>\n  <\/div>\n\n\n<div class=\"slider-wrapper relative\" id=\"slider-1000073345\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n\n  <div class=\"banner has-hover\" id=\"banner-426371520\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1772\" height=\"1181\" src=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/MVD0769-1.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1356927995\" class=\"text-box banner-layer text-box-circle x5 md-x90 lg-x90 y10 md-y10 lg-y10 res-text\">\n                                <div class=\"text-box-content text box-shadow-1\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h3><span style=\"color: #000000;\">Grillen \u00fcberall!<\/span><\/h3>\n<p><span style=\"color: #000000;\">Unser intelligenter tragbarer Gasgrill ist kompakt, elegant und in 1 Minute einsatzbereit.<\/span><\/p>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1356927995 .text-box-content {\n  background-color: rgba(255, 255, 255, 0.94);\n  font-size: 97%;\n}\n#text-box-1356927995 .text-inner {\n  padding: 30px 30px 30px 30px;\n}\n#text-box-1356927995 {\n  width: 50%;\n}\n@media (min-width:550px) {\n  #text-box-1356927995 {\n    width: 26%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-426371520 {\n  padding-top: 500px;\n}\n#banner-426371520 .banner-bg img {\n  object-position: 52% 80%;\n}\n<\/style>\n  <\/div>\n\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\n\t<section class=\"section\" id=\"section_1358864306\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\t<div class=\"ux-shape-divider ux-shape-divider--top ux-shape-divider--style-curve-opacity\">\n\t\t<svg viewBox=\"0 0 1000 100\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n\t\t<path class=\"ux-shape-fill\" opacity=\"0.15\" d=\"M0 14C0 14 88.64 17.48 300 50C560 90 814 77 1003 40L1015 68L1018 104H0V14Z\"\/>\n\t\t<path class=\"ux-shape-fill\" opacity=\"0.3\" d=\"M0 45C0 45 271 90.13 500 77C657 68 830 30 1015 14V100H0V45Z\"\/>\n\t\t<path class=\"ux-shape-fill\" d=\"M0 58C0 58 188.29 90 508 90C798 90 1002 55 1002 55V100H0V58Z\"\/>\n<\/svg>\n\t<\/div>\n\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t<div id=\"gap-779404310\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-779404310 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row align-middle\"  id=\"row-1618936243\">\n\n\n\t<div id=\"col-44337104\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 style=\"text-align: left;\"><span style=\"color: #000000;\">In weniger als einer Minute einsatzbereit<\/span><\/h2>\n<p style=\"text-align: left;\"><span style=\"color: #000000;\">Der nomadiQ BBQ wird mit Gas betrieben und ist in einer Minute einsatzbereit. Drehen Sie den Fu\u00df nach au\u00dfen, entsperren Sie die Kn\u00f6pfe, \u00f6ffnen Sie den NomadiQ, schlie\u00dfen Sie ihn an und beginnen Sie!<\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1624691115\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-1206897370\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 2000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n\n  <div class=\"banner has-hover\" id=\"banner-421251673\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1772\" height=\"1181\" src=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/MVD0769-1.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-227419343\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-227419343 {\n  width: 60%;\n}\n#text-box-227419343 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-227419343 {\n    width: 44%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-421251673 {\n  padding-top: 380px;\n}\n#banner-421251673 .banner-bg img {\n  object-position: 49% 28%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover has-slide-effect slide-zoom-in-fast\" id=\"banner-1661425854\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/Belt-2-scaled-1-1.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1607417459\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1607417459 {\n  width: 60%;\n}\n#text-box-1607417459 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1607417459 {\n    width: 71%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1661425854 {\n  padding-top: 380px;\n}\n#banner-1661425854 .banner-bg img {\n  object-position: 49% 60%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover has-slide-effect slide-zoom-in-fast\" id=\"banner-609658867\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"886\" height=\"591\" src=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/Ultimate-outdoor-pakket-nomadiQ-BBQ-02-1.png\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-378384455\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-378384455 {\n  width: 60%;\n}\n#text-box-378384455 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-378384455 {\n    width: 44%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-609658867 {\n  padding-top: 380px;\n}\n#banner-609658867 .banner-bg img {\n  object-position: 49% 60%;\n}\n<\/style>\n  <\/div>\n\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1358864306 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n}\n#section_1358864306 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1358864306 .ux-shape-divider--top .ux-shape-fill {\n  fill: rgb(223, 14, 19);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_2036501843\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-large align-middle\"  id=\"row-1150972292\">\n\n\n\t<div id=\"col-1946092337\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n<h2>Der intelligenteste tragbare Gasgrill der Welt<\/h2>\n<a href=\"https:\/\/nomadiqbbq.ch\" target=\"_blank\" class=\"button primary lowercase\" rel=\"noopener\">\n\t\t<span>Zum Shop<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1892763564\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><iframe loading=\"lazy\" title=\"NOMADIQ 2023\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/ewQwIIBTt-I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2036501843 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(255, 255, 255);\n}\n#section_2036501843 .section-bg-overlay {\n  background-color: rgba(255, 255, 255, 0.85);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_291454814\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-large align-center row-divided\"  id=\"row-1910717015\">\n\n\n\t<div id=\"col-1917991544\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_702495820\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"563\" src=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_neerzetten-2.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_neerzetten-2.webp 800w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_neerzetten-2-300x211.webp 300w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_neerzetten-2-768x540.webp 768w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_neerzetten-2-510x359.webp 510w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_702495820 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p>Diese Funktion bietet eine intuitive L\u00f6sung f\u00fcr die einfache Positionierung des NomadiQ-Grills.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-722094884\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_722197774\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"563\" src=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_uitklappen-2.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_uitklappen-2.webp 800w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_uitklappen-2-300x211.webp 300w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_uitklappen-2-768x540.webp 768w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_uitklappen-2-510x359.webp 510w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_722197774 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p>Der Schwerpunkt liegt darauf, dass der NomadiQ-Grill leicht zu \u00f6ffnen und schnell in Betrieb zu nehmen ist.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-704241785\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1921013789\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"563\" src=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_ontsteken-2.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_ontsteken-2.webp 800w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_ontsteken-2-300x211.webp 300w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_ontsteken-2-768x540.webp 768w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/nomadiQ-BBQ-hoe-werkt-het_ontsteken-2-510x359.webp 510w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1921013789 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p>Beste Grillpraktiken, elegantes Design und innovative Funktionen des Grills<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_291454814 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/section>\n\t\n\n  \n    <div class=\"row large-columns-5 medium-columns-3 small-columns-3 row-collapse row-full-width slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/MVD0769-1-1024x682.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/MVD0769-1-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"11403,12179,11400,12182,12176\" style=\"normal\" type=\"slider\" col_spacing=\"collapse\" columns=\"5\" columns__sm=\"3\" image_height=\"100%\" srcset=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/MVD0769-1-300x200.jpg 300w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/MVD0769-1-1024x682.jpg 1024w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/MVD0769-1-768x512.jpg 768w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/MVD0769-1-1536x1024.jpg 1536w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/MVD0769-1-510x340.jpg 510w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/MVD0769-1.jpg 1772w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD3007-1024x683.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD3007-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"11403,12179,11400,12182,12176\" style=\"normal\" type=\"slider\" col_spacing=\"collapse\" columns=\"5\" columns__sm=\"3\" image_height=\"100%\" srcset=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD3007-300x200.jpg 300w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD3007-1024x683.jpg 1024w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD3007-768x512.jpg 768w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD3007-510x340.jpg 510w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD3007.jpg 1180w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/Boating-pakket-nomadiQ-BBQ-01-2-1024x1024.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/Boating-pakket-nomadiQ-BBQ-01-2-300x300.webp\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"11403,12179,11400,12182,12176\" style=\"normal\" type=\"slider\" col_spacing=\"collapse\" columns=\"5\" columns__sm=\"3\" image_height=\"100%\" srcset=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/Boating-pakket-nomadiQ-BBQ-01-2-300x300.webp 300w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/Boating-pakket-nomadiQ-BBQ-01-2-1024x1024.webp 1024w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/Boating-pakket-nomadiQ-BBQ-01-2-150x150.webp 150w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/Boating-pakket-nomadiQ-BBQ-01-2-768x768.webp 768w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/Boating-pakket-nomadiQ-BBQ-01-2-510x510.webp 510w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/Boating-pakket-nomadiQ-BBQ-01-2-100x100.webp 100w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/Boating-pakket-nomadiQ-BBQ-01-2-50x50.webp 50w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2023\/12\/Boating-pakket-nomadiQ-BBQ-01-2.webp 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/6-1024x683.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/6-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"11403,12179,11400,12182,12176\" style=\"normal\" type=\"slider\" col_spacing=\"collapse\" columns=\"5\" columns__sm=\"3\" image_height=\"100%\" srcset=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/6-300x200.jpg 300w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/6-1024x683.jpg 1024w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/6-768x512.jpg 768w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/6-1536x1024.jpg 1536w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/6-510x340.jpg 510w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/6.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD8988-683x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD8988-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"11403,12179,11400,12182,12176\" style=\"normal\" type=\"slider\" col_spacing=\"collapse\" columns=\"5\" columns__sm=\"3\" image_height=\"100%\" srcset=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD8988-200x300.jpg 200w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD8988-683x1024.jpg 683w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD8988-768x1152.jpg 768w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD8988-1024x1536.jpg 1024w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD8988-510x765.jpg 510w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/MVD8988.jpg 1181w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\n\n\t<section class=\"section\" id=\"section_216989793\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 0px 1px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-equal\"  id=\"row-512320384\">\n\n\n\t<div id=\"col-1461081510\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"uppercase\">AKTUELL<\/h2>\n<p>Rhythmisieren Sie Ihren Tag mit unseren neuesten Musiknachrichten<\/p>\n<a href=\"https:\/\/solutionscustom.ch\/de\/distributions\/nomadiq-bbq\/\" class=\"button primary lowercase\">\n\t\t<span>Lesen Sie das Ganze<\/span>\n\t<\/a>\n\n\n<h2 class=\"uppercase\">SOCIAL<\/h2>\n<p>Suivez-nous sur les r\u00e9seaux<\/p>\n<div class=\"social-icons follow-icons\" ><a href=\"https:\/\/www.facebook.com\/nomadiqbbqswiss\" target=\"_blank\" data-label=\"Facebook\" class=\"icon primary button circle facebook tooltip\" title=\"Auf Facebook folgen\" aria-label=\"Auf Facebook folgen\" rel=\"noopener nofollow\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"https:\/\/www.instagram.com\/nomadiqbbq_swiss\/\" target=\"_blank\" data-label=\"Instagram\" class=\"icon primary button circle instagram tooltip\" title=\"Auf Instagram folgen\" aria-label=\"Auf Instagram folgen\" rel=\"noopener nofollow\"><i class=\"icon-instagram\" ><\/i><\/a><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-875047846\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  \n    <div class=\"row large-columns-2 medium-columns- small-columns-1 slider row-slider slider-nav-circle slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"border-radius:100%;width:58%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/solutionscustom.ch\/de\/plan-und-schritt-fuer-schritt-tipps-fuer-das-wintergrillen\/\" class=\"plain\" aria-label=\"Plan und Schritt-f\u00fcr-Schritt-Tipps f\u00fcr das Wintergrillen\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"210\" src=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/Asset-4.jpg-300x210.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/Asset-4.jpg-300x210.webp 300w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/Asset-4.jpg-768x538.webp 768w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/Asset-4.jpg-510x357.webp 510w, https:\/\/solutionscustom.ch\/wp-content\/uploads\/2024\/01\/Asset-4.jpg.webp 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/solutionscustom.ch\/de\/plan-und-schritt-fuer-schritt-tipps-fuer-das-wintergrillen\/\" class=\"plain\">Plan und Schritt-f\u00fcr-Schritt-Tipps f\u00fcr das Wintergrillen<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-circle\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">19<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Jan.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_216989793 {\n  padding-top: 43px;\n  padding-bottom: 43px;\n  min-height: 276px;\n  background-color: rgb(241, 241, 241);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"message-box relative dark\" style=\"padding-top:36px;padding-bottom:36px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(74, 74, 74);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n\n<div class=\"row align-middle\"  id=\"row-17534890\">\n\n\n\t<div id=\"col-2141766292\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"uppercase\">Z\u00d6GERN SIE NICHT, UNS ZU KONTAKTIEREN<\/h2>\n<p>Wir stehen Ihnen gerne mit Rat und Tat zur Seite und beantworten alle Ihre Fragen oder kontaktieren einen unserer H\u00e4ndler.<\/p>\n\t<div id=\"gap-1619021055\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1619021055 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a data-animate=\"flipInY\" href=\"https:\/\/solutionscustom.ch\/de\/kontakt\/\" class=\"button white is-outline lowercase\">\n\t\t<span>Kontaktieren Sie uns<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-900320153\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1446367377\" class=\"gap-element clearfix show-for-small\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1446367377 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h2 class=\"uppercase\">Schlie\u00dfen Sie sich UNS als Wiederverk\u00e4ufer an<\/h2>\n<p>M\u00f6chten Sie Ihr Sortiment mit einer Vielfalt an qualitativ hochwertigen Produkten bereichern? Solutions Custom Spezialist in der Bereitstellung von verschiedenen L\u00f6sungen, l\u00e4dt Sie ein, ein Vertriebspartner in unserem umfangreichen Netzwerk zu werden<\/p>\n\t<div id=\"gap-905684586\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-905684586 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a data-animate=\"flipInY\" href=\"https:\/\/solutionscustom.ch\/de\/anfrage-fuer-haendler\/\" class=\"button white is-outline lowercase\">\n\t\t<span>H\u00e4ndler werden<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n<\/div><\/div><\/div>\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":11177,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-11396","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/pages\/11396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/comments?post=11396"}],"version-history":[{"count":5,"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/pages\/11396\/revisions"}],"predecessor-version":[{"id":12453,"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/pages\/11396\/revisions\/12453"}],"up":[{"embeddable":true,"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/pages\/11177"}],"wp:attachment":[{"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/media?parent=11396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}