{"id":11231,"date":"2021-07-26T13:15:50","date_gmt":"2021-07-26T11:15:50","guid":{"rendered":"https:\/\/prod.solutionscustom.ch\/kontakt\/"},"modified":"2024-03-13T20:56:48","modified_gmt":"2024-03-13T19:56:48","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/solutionscustom.ch\/de\/kontakt\/","title":{"rendered":"Kontakt"},"content":{"rendered":"\n\n\t<section class=\"section\" id=\"section_1402008911\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1255251485\">\n\n\n\t<div id=\"col-1735110758\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Unsere Kontaktdaten<\/span><b><\/b><\/h3><\/div>\n\n<p><strong>Laurent Auberson<br><\/strong><strong>Direktor<\/strong><\/p>\n<p>T +41 79 226 76 31<\/p>\n<p>Custom Made Solutions S\u00e0rl<br>Rue de Combremont 4<br>1908 Riddes<\/p>\n<p><a href=\"mailto:info@solutions.best\" target=\"_blank\" rel=\"noopener\">info@solutionscustom.ch<\/a><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-24075859\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Kontaktformular<\/span><b><\/b><\/h3><\/div>\n\n<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-7477\"><form id=\"wpforms-form-7477\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"7477\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/de\/wp-json\/wp\/v2\/pages\/11231\" data-token=\"dc73423a2818ac0c51cd310355a09640\" data-token-time=\"1778689343\"><noscript class=\"wpforms-error-noscript\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-7477-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\">Nom <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-7477-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" required><label for=\"wpforms-7477-field_0\" class=\"wpforms-field-sublabel after\">Vorname<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-7477-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" required><label for=\"wpforms-7477-field_0-last\" class=\"wpforms-field-sublabel after\">Nachname<\/label><\/div><\/div><\/div><div id=\"wpforms-7477-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-7477-field_1\">E-mail <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-7477-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-7477-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-7477-field_2\">Commentaire ou message<\/label><textarea id=\"wpforms-7477-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"7477\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/pages\/11231\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-7477\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/solutionscustom.ch\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Wird geladen\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1402008911 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"message-box relative dark\" style=\"padding-top:36px;padding-bottom:36px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(74, 74, 74);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n\n<div class=\"row\"  id=\"row-1259680792\">\n\n\n\t<div id=\"col-1029867334\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"uppercase\">Z\u00d6GERN SIE NICHT, UNS ZU KONTAKTIEREN<\/h2>\n<p>Wir stehen Ihnen gerne mit Rat und Tat zur Seite und beantworten alle Ihre Fragen oder kontaktieren einen unserer H\u00e4ndler.<\/p>\n\t<div id=\"gap-1878572936\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1878572936 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a data-animate=\"flipInY\" class=\"button white is-outline is-xsmall\"  >\n\t\t<span>Kontaktieren Sie uns<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-873826363\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner text-right\"  >\n\t\t\t\n\t\t\t\n\n<p><span class=\"widget-title\">KONTAKT<\/span><\/p>\n<div class=\"textwidget\">\n<p>Custom Made Solutions S\u00e0rl<br>Rue de Combremont 4 - 1908 Riddes<br>T +41 79 226 76 31<br><a href=\"mailto:info@solutions.best\" target=\"_blank\" rel=\"noopener noreferrer\">info@solutions.best<\/a><\/p>\n<\/div>\n\t<div id=\"gap-1542020377\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1542020377 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n<\/div><\/div><\/div>\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-11231","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/pages\/11231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/comments?post=11231"}],"version-history":[{"count":2,"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/pages\/11231\/revisions"}],"predecessor-version":[{"id":12396,"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/pages\/11231\/revisions\/12396"}],"wp:attachment":[{"href":"https:\/\/solutionscustom.ch\/de\/wp-json\/wp\/v2\/media?parent=11231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}